{"id":4633,"date":"2025-06-11T09:57:58","date_gmt":"2025-06-11T09:57:58","guid":{"rendered":"https:\/\/vapehosale.com\/?post_type=product&#038;p=4633"},"modified":"2025-09-10T09:53:38","modified_gmt":"2025-09-10T09:53:38","slug":"fizzy-nova-40000-puffs-best-disposable-vape","status":"publish","type":"product","link":"https:\/\/vapehosale.com\/nl\/product\/fizzy-nova-40000-puffs-best-disposable-vape\/","title":{"rendered":"Fizzy Nova 40000 trekjes beste wegwerp vape"},"content":{"rendered":"<h2>Fizzy Nova 40000 Puffs Wegwerp Vape Beschrijving<\/h2>\n<p>Fizzy Nova 40000 Puffs Vape bevat een kolossale 40 ml premium e-liquid, wat resulteert in een toonaangevende 40.000 bevredigende trekjes. Het beschikt over geavanceerde dubbele mesh-coil technologie voor versterkte smaakhelderheid en dichtere damp productie. Regel uw ervaring met verstelbare luchtstroom en een handige moduswissel functie. De ge\u00efntegreerde 850mAh oplaadbare batterij zorgt voor consistente stroom, gemakkelijk bij te vullen via USB Type-C. Houd uw e-liquid- en batterijniveaus moeiteloos bij met het duidelijke LED-display. Kies uw voorkeursnicotinesterkte: 2% of 5%.<br \/>\n<img decoding=\"async\" class=\"alignnone size-full wp-image-4629\" src=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-wholesale-Europe-market.webp\" alt=\"Fizzy Nova 40k Puffs groothandel Europa markt\" width=\"1000\" height=\"664\" srcset=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-wholesale-Europe-market.webp 1000w, https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-wholesale-Europe-market-300x199.webp 300w, https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-wholesale-Europe-market-768x510.webp 768w, https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-wholesale-Europe-market-600x398.webp 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><br \/>\n<img decoding=\"async\" class=\"alignnone size-full wp-image-4626\" src=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-rechargeable-adjustable-airflow-.webp\" alt=\"Fizzy Nova 40k Puffs oplaadbare instelbare airflow\" width=\"1000\" height=\"622\" srcset=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-rechargeable-adjustable-airflow-.webp 1000w, https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-rechargeable-adjustable-airflow--300x187.webp 300w, https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-rechargeable-adjustable-airflow--768x478.webp 768w, https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-rechargeable-adjustable-airflow--600x373.webp 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<h2>Fizzy Nova 40k Vape Kenmerken:<\/h2>\n<p>Mesh coil<br \/>\nModuswissel<br \/>\nLuchtstroom<br \/>\nE-liquid: 40 ml<br \/>\nBatterij: 850mAh<br \/>\nNicotine: 2%\/5%<br \/>\nOplaadbaar:Type-C<br \/>\nLED-display<br \/>\nExp. 2 jaar<br \/>\nProductgewicht: 120 g\/stuk<br \/>\nProductafmetingen: 52,5 x 24,5 x 104,3 mm<br \/>\nAANTAL: 180 stuks\/doos, 10 stuks\/doos<br \/>\nG.W: 22 kg\/doos<\/p>\n<h2>Fizzy Nova 40000 Vape Smaaklijst:<\/h2>\n<p>1. Aardbei IJs<br \/>\n2. Blauwe kokosnoot<br \/>\n3. Aardbei Kiwi<br \/>\n4. Blauwe bes IJs<br \/>\n5. Watermeloen IJs<br \/>\n6. Perzik Mango Watermeloen<br \/>\n7. Kiwi Passievrucht Guave<br \/>\n8. Framboos Citroen<br \/>\n9. Drievoudige Bes<br \/>\n10. Perzikijs<br \/>\n11. Druif Limoen<br \/>\n12. Blauwe Razz Limonade<br \/>\n<img decoding=\"async\" class=\"alignnone size-large wp-image-4622\" src=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-dual-mesh-coil-flavor--863x1024.webp\" alt=\"Fizzy Nova 40k Puffs dual mesh coil smaak\" width=\"863\" height=\"1024\" srcset=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-dual-mesh-coil-flavor--863x1024.webp 863w, https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-dual-mesh-coil-flavor--253x300.webp 253w, https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-dual-mesh-coil-flavor--768x912.webp 768w, https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-dual-mesh-coil-flavor--600x712.webp 600w, https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-dual-mesh-coil-flavor-.webp 1000w\" sizes=\"(max-width: 863px) 100vw, 863px\" \/><\/p>\n<h3><strong>5 Veelgestelde vragen over Fizzy Vape Nova 40k Puffs<\/strong><\/h3>\n<ol start=\"1\">\n<li>\n<p class=\"ds-markdown-paragraph\"><strong>V: Hoe realistisch is de claim van de Fizzy Nova 40000 Puffs wegwerpvape?<\/strong><br \/>\nA: De schatting van 40000 trekjes is gebaseerd op gemiddeld gebruik met de aanzienlijke e-liquid capaciteit van 40 ml en een effici\u00ebnt dubbel mesh coil systeem. Werkelijke resultaten zijn afhankelijk van de individuele trekjesduur.<\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong>V: Hoe lang duurt het opladen van de Fizzy Nova 40k Puffs wegwerpvapes 850mAh batterij?<\/strong><br \/>\nA: Met de meegeleverde USB Type-C kabel is de batterij in ongeveer 45-60 minuten volledig opgeladen, wat zorgt voor minimale stilstand.<\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong>V: In welke nicotine sterktes zijn Fizzy wegwerpvapes Nova 40000 Puffs verkrijgbaar?<\/strong><br \/>\nA: De\u00a0<strong>Fizzy Nova 40.000 trekjes e-sigaret<\/strong>\u00a0biedt twee nicotine opties: 21% (20 mg) en 51% (50 mg) om aan verschillende voorkeuren te voldoen.<\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong>V: Kan ik de Fizzy Vape Nova 40000 Puffs trek strakheid aanpassen?<\/strong><br \/>\nA: Ja! Het apparaat beschikt over een verstelbare luchtstroomregeling, waarmee u de trek kunt aanpassen van een strakke Mouth-to-Lung (MTL) tot een lossere Restricted Direct Lung (RDL) gevoel.<\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong>V: Wat doet de Fizzy Nova 40k Puffs wegwerpvape \"moduswissel\" functie?<\/strong><br \/>\nA: De moduswisselknop activeert specifieke vooraf ingestelde vermogensprofielen die geoptimaliseerd zijn voor de dubbele mesh coil, waardoor de smaakintensiteit of damp productie wordt verbeterd, afhankelijk van uw keuze.<\/p>\n<\/li>\n<\/ol>\n<h3><strong>Waarom kiezen voor Fizzy Nova 40000 Puffs Vapes?<\/strong><\/h3>\n<ol start=\"1\">\n<li>\n<p class=\"ds-markdown-paragraph\"><strong>Onge\u00ebvenaarde Levensduur:<\/strong> Geniet van tot wel 40000 premium trekjes uit \u00e9\u00e9n enkel, enorm apparaat van 40 ml \u2013 ultieme waarde en gemak.<\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong>Superieure Smaak<\/strong> Dubbele mesh coils leveren uitzonderlijk rijke, pure smaaktonen en consistent dichte, bevredigende dampwolken.<\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong>Premium Bedieningsfuncties:<\/strong> Pas de luchtstroom aan, wissel van dampmodus en controleer de niveaus eenvoudig via het LED-scherm - alles aangedreven door een oplaadbare 850mAh-batterij.<\/p>\n<\/li>\n<\/ol>\n<h5><strong>Inhoud van de verpakking:<\/strong><\/h5>\n<p>1 x Fizzy Wegwerp Vape EU-magazijn Nova 40k puffs<\/p>\n<p>Andere Wegwerp Vape in Nederland magazijn Groothandel<\/p>\n<p><a href=\"https:\/\/vapehosale.com\/nl\/product-category\/fizzy-vape\/\">Fizzy Wegwerp Vape Groothandel Magazijn<span class=\"x19la9d6 x1fc57z9 x6ikm8r x10wlt62 x19co3pv x1g5zs5t xfibh0p xiy17q3 x1xsqp64 x1lkfr7t xexx8yu xyri2b x18d9i69 x1c1uobl\"><span class=\"xrtxmta x1bhl96m\"><img decoding=\"async\" class=\"emoji\" role=\"img\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/16.0.1\/svg\/1f448.svg\" alt=\"\ud83d\udc48\" \/><br \/>\n<\/span><\/span><\/a><\/p>\n<p><a href=\"https:\/\/vapehosale.com\/nl\/product-category\/40k-puffs-disposable-vape-wholesale\/\">40000 Puffs Wegwerp vape Topverkoop<\/a><br \/>\n<a href=\"https:\/\/vapehosale.com\/nl\/product-category\/disposable-vape-in-european-warehouse\/\">Disposable Vape Groothandel In EU magazijn<\/a><\/p>\n<p>Vape met speciale vorm:<a href=\"https:\/\/vapehosale.com\/nl\/product\/bulk-buy-bang-king-12000\/\">flesvorm<\/a>\/Colablikje\/<a href=\"https:\/\/vapehosale.com\/nl\/product\/sidia-12000-puffs-disposable-device\/\">RGB-licht<\/a>\/Kristal<\/p>\n<h3>Verzendgegevens:<\/h3>\n<p>DHL\/UPS\/DPD, <span style=\"color: #ff0000\">3-5 werkdagen aangekomen op uw adres, verzonden vanuit het magazijn in Nederland<\/span><\/p>\n<h4>Betalingsgegevens:<\/h4>\n<p>Wij ondersteunen betaling via IBAN of Western Union, geen contante betaling bij levering.<\/p>\n<p>Alle producten in onze winkel zijn 100% origineel en authentiek, dus tien keer compensatie voor namaakgoederen is ons winkelbeleid.<\/p>\n<p>Voor meer gedetailleerde groothandelsprijs, MOQ, beschikbare smaken, neem contact op met onze salesmanager Vicky <a href=\"https:\/\/wa.me\/8618077105750\">WhatsApp: +8618077105750<\/a><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-2638\" src=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2023\/09\/885301ea6f5e0b91f5ab2b1c85e665c.png\" alt=\"RandM Fabriek\" width=\"670\" height=\"658\" srcset=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2023\/09\/885301ea6f5e0b91f5ab2b1c85e665c.png 670w, https:\/\/vapehosale.com\/wp-content\/uploads\/2023\/09\/885301ea6f5e0b91f5ab2b1c85e665c-300x295.png 300w, https:\/\/vapehosale.com\/wp-content\/uploads\/2023\/09\/885301ea6f5e0b91f5ab2b1c85e665c-600x589.png 600w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p class=\"\" data-start=\"2210\" data-end=\"2450\">Fizzy Nova 40000 Puffs Wegwerpapparaat met een revolutionaire dubbele mesh-coil, verstelbare luchtstroom, modusselectie, LED-display en USB-C oplaadbare 850mAh batterij. Bevat 40 ml e-liquid in 2% of 5% nicotine. Ervaar extreme levensduur en premium smaak<span style=\"color: #ff0000\">\uff08Gratis verzending\uff09<\/span><\/p>\n<p><span style=\"color: #ff0000\">Eu Magazijn Wegwerp Vape snelle verzending, minimale bestelling 50 stuks.<\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-2638\" src=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2023\/09\/885301ea6f5e0b91f5ab2b1c85e665c-300x295.png\" alt=\"RandM Fabriek\" width=\"300\" height=\"295\" srcset=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2023\/09\/885301ea6f5e0b91f5ab2b1c85e665c-300x295.png 300w, https:\/\/vapehosale.com\/wp-content\/uploads\/2023\/09\/885301ea6f5e0b91f5ab2b1c85e665c-600x589.png 600w, https:\/\/vapehosale.com\/wp-content\/uploads\/2023\/09\/885301ea6f5e0b91f5ab2b1c85e665c.png 670w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":4619,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","_lmt_disableupdate":"no","_lmt_disable":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","_joinchat":[]},"product_cat":[15,41,79,146,97,55],"product_tag":[76,35,33],"class_list":["post-4633","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-vape-shop-wholesale","product_cat-europe-hot-sale-vape","product_cat-disposable-vape-in-european-warehouse","product_cat-fizzy-vape","product_cat-40k-puffs-disposable-vape-wholesale","product_cat-minimum-order-quantity-50pcs","product_tag-airflow-control-vape","product_tag-rechargeable-disposable-device","product_tag-rgb-light-disposable-vape","desktop-align-left","tablet-align-left","mobile-align-left"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fizzy Nova 40000 Puffs Best Disposable Vape - Vape Wholesale<\/title>\n<meta name=\"description\" content=\"Wholesale Fizzy Nova 40000 Puffs Vape: dual mesh coil, adjustable airflow, LED display. Massive 40ml capacity. Shop premium flavor &amp; longevity now!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vapehosale.com\/nl\/product\/fizzy-nova-40000-puffs-best-disposable-vape\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fizzy Nova 40000 Puffs Best Disposable Vape - Vape Wholesale\" \/>\n<meta property=\"og:description\" content=\"Wholesale Fizzy Nova 40000 Puffs Vape: dual mesh coil, adjustable airflow, LED display. Massive 40ml capacity. Shop premium flavor &amp; longevity now!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vapehosale.com\/nl\/product\/fizzy-nova-40000-puffs-best-disposable-vape\/\" \/>\n<meta property=\"og:site_name\" content=\"Vape Wholesale\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-10T09:53:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-best-quality-disposable-vape-.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verwachte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vapehosale.com\/product\/fizzy-nova-40000-puffs-best-disposable-vape\/\",\"url\":\"https:\/\/vapehosale.com\/product\/fizzy-nova-40000-puffs-best-disposable-vape\/\",\"name\":\"Fizzy Nova 40000 Puffs Best Disposable Vape - Vape Wholesale\",\"isPartOf\":{\"@id\":\"https:\/\/vapehosale.com\/#website\"},\"datePublished\":\"2025-06-11T09:57:58+00:00\",\"dateModified\":\"2025-09-10T09:53:38+00:00\",\"description\":\"Wholesale Fizzy Nova 40000 Puffs Vape: dual mesh coil, adjustable airflow, LED display. Massive 40ml capacity. Shop premium flavor & longevity now!\",\"breadcrumb\":{\"@id\":\"https:\/\/vapehosale.com\/product\/fizzy-nova-40000-puffs-best-disposable-vape\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vapehosale.com\/product\/fizzy-nova-40000-puffs-best-disposable-vape\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vapehosale.com\/product\/fizzy-nova-40000-puffs-best-disposable-vape\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/vapehosale.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/vapehosale.com\/vape-shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fizzy Nova 40000 Puffs Best Disposable Vape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vapehosale.com\/#website\",\"url\":\"https:\/\/vapehosale.com\/\",\"name\":\"Vape Wholesale\",\"description\":\"Buy Vape Wholesale Price Near you\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/vapehosale.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fizzy Nova 40000 Puffs Beste Wegwerp Vape - Vape Groothandel","description":"Groothandel Fizzy Nova 40000 Puffs Vape: dual mesh coil, aanpasbare luchtstroom, LED-display. Enorme capaciteit van 40 ml. Koop premium smaak.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vapehosale.com\/nl\/product\/fizzy-nova-40000-puffs-best-disposable-vape\/","og_locale":"nl_NL","og_type":"article","og_title":"Fizzy Nova 40000 Puffs Best Disposable Vape - Vape Wholesale","og_description":"Wholesale Fizzy Nova 40000 Puffs Vape: dual mesh coil, adjustable airflow, LED display. Massive 40ml capacity. Shop premium flavor & longevity now!","og_url":"https:\/\/vapehosale.com\/nl\/product\/fizzy-nova-40000-puffs-best-disposable-vape\/","og_site_name":"Vape Wholesale","article_modified_time":"2025-09-10T09:53:38+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-best-quality-disposable-vape-.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Verwachte leestijd":"4 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vapehosale.com\/product\/fizzy-nova-40000-puffs-best-disposable-vape\/","url":"https:\/\/vapehosale.com\/product\/fizzy-nova-40000-puffs-best-disposable-vape\/","name":"Fizzy Nova 40000 Puffs Beste Wegwerp Vape - Vape Groothandel","isPartOf":{"@id":"https:\/\/vapehosale.com\/#website"},"datePublished":"2025-06-11T09:57:58+00:00","dateModified":"2025-09-10T09:53:38+00:00","description":"Groothandel Fizzy Nova 40000 Puffs Vape: dual mesh coil, aanpasbare luchtstroom, LED-display. Enorme capaciteit van 40 ml. Koop premium smaak.","breadcrumb":{"@id":"https:\/\/vapehosale.com\/product\/fizzy-nova-40000-puffs-best-disposable-vape\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vapehosale.com\/product\/fizzy-nova-40000-puffs-best-disposable-vape\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vapehosale.com\/product\/fizzy-nova-40000-puffs-best-disposable-vape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vapehosale.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/vapehosale.com\/vape-shop\/"},{"@type":"ListItem","position":3,"name":"Fizzy Nova 40000 Puffs Best Disposable Vape"}]},{"@type":"WebSite","@id":"https:\/\/vapehosale.com\/#website","url":"https:\/\/vapehosale.com\/","name":"Groothandel in vapes","description":"Koop Vape Groothandelsprijs bij u in de buurt","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vapehosale.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"}]}},"uagb_featured_image_src":{"full":["https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-best-quality-disposable-vape-.webp",1000,1000,false],"thumbnail":["https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-best-quality-disposable-vape--150x150.webp",150,150,true],"medium":["https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-best-quality-disposable-vape--300x300.webp",300,300,true],"medium_large":["https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-best-quality-disposable-vape--768x768.webp",768,768,true],"large":["https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-best-quality-disposable-vape-.webp",1000,1000,false],"1536x1536":["https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-best-quality-disposable-vape-.webp",1000,1000,false],"2048x2048":["https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-best-quality-disposable-vape-.webp",1000,1000,false],"trp-custom-language-flag":["https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-best-quality-disposable-vape-.webp",12,12,false],"woocommerce_thumbnail":["https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-best-quality-disposable-vape--300x300.webp",300,300,true],"woocommerce_single":["https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-best-quality-disposable-vape--600x600.webp",600,600,true],"woocommerce_gallery_thumbnail":["https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-best-quality-disposable-vape--100x100.webp",100,100,true],"wcpr-photo-reviews":["https:\/\/vapehosale.com\/wp-content\/uploads\/2025\/06\/Fizzy-Nova-40k-Puffs-best-quality-disposable-vape-.webp",500,500,false]},"uagb_author_info":{"display_name":"Vicky hosale","author_link":"https:\/\/vapehosale.com\/nl\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Fizzy Nova 40000 Puffs Disposable Device featuring a revolutionary dual mesh coil, adjustable airflow, mode selection, LED display, and USB-C rechargeable 850mAh battery. Holds 40ml of e-liquid in 2% or 5% nicotine. Experience extreme longevity and premium flavor\uff08Free shipping\uff09 Eu Warehouse Disposable Vape fast shipping , min order 50pcs. &nbsp; &nbsp;","_links":{"self":[{"href":"https:\/\/vapehosale.com\/nl\/wp-json\/wp\/v2\/product\/4633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vapehosale.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vapehosale.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/vapehosale.com\/nl\/wp-json\/wp\/v2\/comments?post=4633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vapehosale.com\/nl\/wp-json\/wp\/v2\/media\/4619"}],"wp:attachment":[{"href":"https:\/\/vapehosale.com\/nl\/wp-json\/wp\/v2\/media?parent=4633"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vapehosale.com\/nl\/wp-json\/wp\/v2\/product_cat?post=4633"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vapehosale.com\/nl\/wp-json\/wp\/v2\/product_tag?post=4633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}