{"id":3047,"date":"2024-10-17T07:31:44","date_gmt":"2024-10-17T07:31:44","guid":{"rendered":"https:\/\/vapehosale.com\/?post_type=product&#038;p=3047"},"modified":"2025-08-11T08:35:44","modified_gmt":"2025-08-11T08:35:44","slug":"jnr-shisha-hookah-elfbox-15000-puffs","status":"publish","type":"product","link":"https:\/\/vapehosale.com\/fr\/product\/jnr-shisha-hookah-elfbox-15000-puffs\/","title":{"rendered":"Chicha JNR ELFBOX 15000 Puffs Vape Jetable"},"content":{"rendered":"<h2 style=\"text-align: center\">ELF BOX Chicha Narguil\u00e9 15000 Puffs Vape Jetable<\/h2>\n<p>&nbsp;<\/p>\n<p>La Vape Jetable ELF BOX 15000 Puffs est un appareil de vapotage haute performance et pratique, con\u00e7u sp\u00e9cifiquement pour les utilisateurs qui aiment l'exp\u00e9rience. Il est dot\u00e9 d'une <strong>narguil\u00e9 chicha<\/strong> exp\u00e9rience. Il dispose d'un <strong>bobine \u00e0 mailles de 0,6 ohm<\/strong>, assurant une vapeur cors\u00e9e et de riches <strong>saveurs de narguil\u00e9 chicha<\/strong> \u00e0 chaque bouff\u00e9e. Avec une capacit\u00e9 d'e-liquide de 26 ml, cet appareil offre jusqu'\u00e0 15000 bouff\u00e9es, ce qui en fait l'une des <strong>meilleures options de narguil\u00e9 chicha<\/strong> sur le march\u00e9.<\/p>\n<p>Cet appareil propose des niveaux de nicotine de 0%, 2% ou 5% pour r\u00e9pondre aux diff\u00e9rentes pr\u00e9f\u00e9rences des utilisateurs, y compris ceux qui pr\u00e9f\u00e8rent le <strong>narguil\u00e9 chicha sans nicotine<\/strong>. La batterie rechargeable int\u00e9gr\u00e9e de 18250-600mAh est aliment\u00e9e par un port de charge Type-C, assurant une recharge rapide et efficace pour une utilisation prolong\u00e9e.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-3049\" src=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/10\/ELF-BOX-Shisha-Hookah-15000-Puffs-Disposable-Vape.png\" alt=\"ELF BOX Chicha Narguil\u00e9 15000 Puffs Vape Jetable\" width=\"900\" height=\"626\" srcset=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/10\/ELF-BOX-Shisha-Hookah-15000-Puffs-Disposable-Vape.png 900w, https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/10\/ELF-BOX-Shisha-Hookah-15000-Puffs-Disposable-Vape-300x209.png 300w, https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/10\/ELF-BOX-Shisha-Hookah-15000-Puffs-Disposable-Vape-768x534.png 768w, https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/10\/ELF-BOX-Shisha-Hookah-15000-Puffs-Disposable-Vape-600x417.png 600w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h3>\u00a0Saveur de Chicha Narguil\u00e9 Disponible :<\/h3>\n<p>1.Glace \u00e0 la m\u00fbre<\/p>\n<p>2.Myrtille sur glace<\/p>\n<p>3.Kiwi Fruit de la Passion<\/p>\n<p>4.Fraise Kiwi<\/p>\n<p>5.Limonade au cassis et \u00e0 la framboise<\/p>\n<p>6.Past\u00e8que glac\u00e9e<\/p>\n<p>7.Fraise Past\u00e8que<\/p>\n<p>8.Fraise glac\u00e9e<\/p>\n<p>9.P\u00eache Mangue Ananas<\/p>\n<p>10.Raisin glac\u00e9<\/p>\n<p>11.Mangue Banane<\/p>\n<p>12.Fruits des bois<\/p>\n<h3>Caract\u00e9ristiques principales d'ELF BOX 15000 Puffs :<\/h3>\n<ul>\n<li><strong>15000 bouff\u00e9es<\/strong>: Offre une exp\u00e9rience de vapotage prolong\u00e9e sans recharges fr\u00e9quentes ni changement d'appareil.<\/li>\n<li><strong>R\u00e9sistance Mesh 0.6ohm<\/strong>: La r\u00e9sistance mesh assure des tirages fluides et une production de vapeur constante pour une exp\u00e9rience premium.<\/li>\n<li><strong>26ml E-liquide<\/strong>: La grande capacit\u00e9 de e-liquide r\u00e9duit le besoin de recharges constantes.<\/li>\n<li><strong>Options de nicotine<\/strong>: Disponible en 0%, 2% et 5% de taux de nicotine, r\u00e9pondant \u00e0 toutes les pr\u00e9f\u00e9rences des utilisateurs, y compris <strong>narguil\u00e9 chicha sans nicotine<\/strong> amateurs.<\/li>\n<li><strong>Rechargeable en Type-C<\/strong>: \u00c9quip\u00e9 d'une batterie 18250-600mAh, l'appareil prend en charge la recharge rapide via le port Type-C.<\/li>\n<\/ul>\n<h3>Pourquoi choisir le Vape Jetable ELF BOX 15000 Puffs?<\/h3>\n<ul>\n<li><strong>Qu'est-ce que la Chicha Narguil\u00e9 ELFBOX 15000 Puffs?<\/strong> C'est un appareil de vape jetable pratique et performant qui imite parfaitement l'exp\u00e9rience traditionnelle <strong>narguil\u00e9 chicha<\/strong> d'une chicha.<\/li>\n<li>Id\u00e9al pour les utilisateurs qui veulent savourer <strong>narguil\u00e9 chicha<\/strong> leur chicha \u00e0 tout moment et n'importe o\u00f9, sans les tracas du nettoyage ou de l'entretien.<\/li>\n<li>C'est un excellent choix lorsque vous recherchez le <strong>meilleures options de narguil\u00e9 chicha<\/strong> meilleur narguil\u00e9 jetable sur le march\u00e9.<\/li>\n<\/ul>\n<h3>Acheter<\/h3>\n<p>Ce produit est id\u00e9al pour les grossistes, offrant un prix de chicha comp\u00e9titif. Pour les commandes en gros, contactez-nous pour obtenir des offres sp\u00e9ciales sur les chichas \u00e0 vendre.<br \/>\nVous pouvez facilement acheter avec notre responsable des ventes vicky, avec des services de livraison de chicha narguil\u00e9 disponibles pour votre commodit\u00e9.<br \/>\nVous voulez trouver une chicha narguil\u00e9 pr\u00e8s de chez vous ? Utilisez notre service pour trouver rapidement une chicha narguil\u00e9 pr\u00e8s de chez moi.<\/p>\n<p>La cigarette \u00e9lectronique jetable ELFBOX 15000 Puffs combine une technologie de bobine maill\u00e9e avanc\u00e9e avec une batterie haute capacit\u00e9 et un grand r\u00e9servoir d'e-liquide, ce qui en fait un excellent <strong>narguil\u00e9 chicha \u00e9lectrique<\/strong> appareil. Que vous pr\u00e9f\u00e9riez <strong>narguil\u00e9 chicha sans nicotine<\/strong> ou que vous recherchiez les meilleures <strong>marques de narguil\u00e9 chicha<\/strong>, ELFBOX r\u00e9pond \u00e0 tous vos besoins. Si vous pr\u00e9voyez d' <strong>acheter un narguil\u00e9 chicha<\/strong> \u00e9quipement, le ELF BOX Narguil\u00e9 Chicha 15000 Puffs est l'une des meilleures options en 2024.<\/p>\n<p><strong>Essayez-le maintenant et profitez de la meilleure exp\u00e9rience de narguil\u00e9 chicha d\u00e8s aujourd'hui !<\/strong><\/p>\n<h5><strong>Contenu de l'emballage :<\/strong><\/h5>\n<p>1 x ELF BOX LS15000 Cigarette \u00c9lectronique Jetable<\/p>\n<p>\u2705Vente en gros sortie d'usine Whatsapp :<a href=\"https:\/\/wa.me\/8618077105750\">+8618077105750<\/a><\/p>\n<p>\u2705 Grossistes et revendeurs sont les bienvenus pour personnaliser les commandes<br \/>\n\u2705 Fournir des produits de la plus haute qualit\u00e9 et les services les plus professionnels.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-2638\" src=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2023\/09\/885301ea6f5e0b91f5ab2b1c85e665c.png\" alt=\"Usine RandM\" width=\"670\" height=\"658\" srcset=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2023\/09\/885301ea6f5e0b91f5ab2b1c85e665c.png 670w, https:\/\/vapehosale.com\/wp-content\/uploads\/2023\/09\/885301ea6f5e0b91f5ab2b1c85e665c-300x295.png 300w, https:\/\/vapehosale.com\/wp-content\/uploads\/2023\/09\/885301ea6f5e0b91f5ab2b1c85e665c-600x589.png 600w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/p>\n<p><a href=\"https:\/\/vapehosale.com\/fr\/product\/randm-tornado-7000-puffs-disposable-vape\/\">Vape en vente chaude<\/a><br \/>\n<a href=\"https:\/\/vapehosale.com\/fr\/product\/original-shisha-hookah-15000-puffs-jnr-disposable-vape\/\">Shisha Chicha 15000 Bouff\u00e9es<\/a><br \/>\n<a href=\"https:\/\/vapehosale.com\/fr\/product\/wga-crystal-plus-20k-disposable-vapes\/\">WGA CryStal Plus 20k Bo\u00eete jetable<\/a><br \/>\n<a href=\"https:\/\/vapehosale.com\/fr\/product\/original-crystal-bar-600-puffs-disposable-vape\/\">Crystal Bar 600 Bouff\u00e9es Barre jetable<\/a><br \/>\nContact pour le catalogue produits :<a href=\"https:\/\/wa.me\/8618077105750\">Acheter maintenant<\/a><\/p>\n<p>Mod\u00e8le de vape de forme sp\u00e9ciale :<a href=\"https:\/\/vapehosale.com\/fr\/product\/bulk-buy-bang-king-12000\/\">forme de bouteille<\/a>\/canette de Coca\/<a href=\"https:\/\/vapehosale.com\/fr\/product\/sidia-12000-puffs-disposable-device\/\">lumi\u00e8re RVB<\/a>\/Cristal<\/p>\n<h4>D\u00e9tails de l'exp\u00e9dition :<br \/>\nNous sommes une usine de vape de Chine, ne prenons pas en charge le paiement \u00e0 la livraison.<\/h4>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-2636\" src=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/08\/08cd586e84373c021e8ec9b990d8dae.png\" alt=\"Exp\u00e9dition rapide de vape jetable\" width=\"726\" height=\"265\" srcset=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/08\/08cd586e84373c021e8ec9b990d8dae.png 726w, https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/08\/08cd586e84373c021e8ec9b990d8dae-300x110.png 300w, https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/08\/08cd586e84373c021e8ec9b990d8dae-600x219.png 600w\" sizes=\"(max-width: 726px) 100vw, 726px\" \/><\/p>\n<h4>D\u00e9tails de paiement :<\/h4>\n<p>Nous acceptons les paiements par virement bancaire ou Western Union, nous sommes une usine de vapes de Chine, <span style=\"color: #ff0000\">ne prenons pas en charge le paiement \u00e0 la livraison.<\/span><\/p>\n<p>Tous les produits de notre boutique sont 100% originaux et authentiques, la politique de notre magasin est donc de rembourser dix fois la valeur en cas de contrefa\u00e7on.<\/p>\n<h5><span style=\"color: #ff0000\">Puis-je avoir un \u00e9chantillon d'abord ? Commande minimum 50 pi\u00e8ces, pas d'\u00e9chantillon gratuit.<\/span><\/h5>\n<h3>Service apr\u00e8s-vente :<\/h3>\n<p><span style=\"color: #ff0000\">Remarque : Pas de retours ni d'\u00e9changes pour les probl\u00e8mes non li\u00e9s \u00e0 la qualit\u00e9<br \/>\n<span style=\"color: #000000\">Les produits sont fabriqu\u00e9s \u00e0 la demande du client. Aucun remboursement ne sera accord\u00e9 s'il n'y a pas de probl\u00e8me de qualit\u00e9 apr\u00e8s la r\u00e9ception des marchandises par le client.<\/span><\/span><\/p>\n<p>1. Il est interdit aux mineurs de moins de 21 ans d'acheter des appareils et accessoires \u00e0 usage unique.<\/p>\n<p>2. Certaines petites \u00eeles des pays europ\u00e9ens peuvent exiger des frais suppl\u00e9mentaires pour les zones \u00e9loign\u00e9es, veuillez nous consulter avant d'acheter.<\/p>\n<p>3. Les prix sur notre site Web n'incluent pas les frais d'exp\u00e9dition. Veuillez contacter la responsable des ventes Vicky pour vous renseigner sur les frais d'exp\u00e9dition avant de passer une commande.<\/p>","protected":false},"excerpt":{"rendered":"<p>La Vape Jetable ELFBOX 15000 Puffs offre jusqu'\u00e0 15000 bouff\u00e9es avec 26 ml d'e-liquide, une bobine \u00e0 mailles de 0,6 ohm et une batterie rechargeable Type-C. Disponible en options sans nicotine pour une exp\u00e9rience de narguil\u00e9 premium <strong>narguil\u00e9 chicha<\/strong> exp\u00e9rience<span style=\"color: #ff0000\">(le prix du site web n'inclut pas les frais d'exp\u00e9dition)<\/span><\/p>\n<p><span style=\"color: #ff0000\">contactez-moi pour une commande minimum de seulement 50 pi\u00e8ces ! pas de vente en dessous de 50 pi\u00e8ces, <\/span>Vente en gros uniquement !<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-2638\" src=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2023\/09\/885301ea6f5e0b91f5ab2b1c85e665c-300x295.png\" alt=\"Usine RandM\" width=\"300\" height=\"295\" srcset=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2023\/09\/885301ea6f5e0b91f5ab2b1c85e665c-300x295.png 300w, https:\/\/vapehosale.com\/wp-content\/uploads\/2023\/09\/885301ea6f5e0b91f5ab2b1c85e665c-600x589.png 600w, https:\/\/vapehosale.com\/wp-content\/uploads\/2023\/09\/885301ea6f5e0b91f5ab2b1c85e665c.png 670w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":3050,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","_lmt_disableupdate":"no","_lmt_disable":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","_joinchat":[]},"product_cat":[15,41,148,55],"product_tag":[76,35,33],"class_list":["post-3047","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-vape-shop-wholesale","product_cat-europe-hot-sale-vape","product_cat-elfbox-vape","product_cat-minimum-order-quantity-50pcs","product_tag-airflow-control-vape","product_tag-rechargeable-disposable-device","product_tag-rgb-light-disposable-vape","desktop-align-left","tablet-align-left","mobile-align-left"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>JNR Shisha Hookah ELFBOX 15000 Puffs Disposable Vape - Vape Wholesale<\/title>\n<meta name=\"description\" content=\"ELF BOX Shisha Hookah 15000 Disposable Vape with rich hookah shisha flavors, rechargeable battery, and nicotine-free options. Long-lasting, and powerful.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vapehosale.com\/fr\/product\/jnr-shisha-hookah-elfbox-15000-puffs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JNR Shisha Hookah ELFBOX 15000 Puffs Disposable Vape - Vape Wholesale\" \/>\n<meta property=\"og:description\" content=\"ELF BOX Shisha Hookah 15000 Disposable Vape with rich hookah shisha flavors, rechargeable battery, and nicotine-free options. Long-lasting, and powerful.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vapehosale.com\/fr\/product\/jnr-shisha-hookah-elfbox-15000-puffs\/\" \/>\n<meta property=\"og:site_name\" content=\"Vape Wholesale\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-11T08:35:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/10\/ELF-BOX-Shisha-Hookah-15000-Vape-Flavors.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vapehosale.com\/product\/jnr-shisha-hookah-elfbox-15000-puffs\/\",\"url\":\"https:\/\/vapehosale.com\/product\/jnr-shisha-hookah-elfbox-15000-puffs\/\",\"name\":\"JNR Shisha Hookah ELFBOX 15000 Puffs Disposable Vape - Vape Wholesale\",\"isPartOf\":{\"@id\":\"https:\/\/vapehosale.com\/#website\"},\"datePublished\":\"2024-10-17T07:31:44+00:00\",\"dateModified\":\"2025-08-11T08:35:44+00:00\",\"description\":\"ELF BOX Shisha Hookah 15000 Disposable Vape with rich hookah shisha flavors, rechargeable battery, and nicotine-free options. Long-lasting, and powerful.\",\"breadcrumb\":{\"@id\":\"https:\/\/vapehosale.com\/product\/jnr-shisha-hookah-elfbox-15000-puffs\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vapehosale.com\/product\/jnr-shisha-hookah-elfbox-15000-puffs\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vapehosale.com\/product\/jnr-shisha-hookah-elfbox-15000-puffs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/vapehosale.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/vapehosale.com\/vape-shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"JNR Shisha Hookah ELFBOX 15000 Puffs Disposable Vape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vapehosale.com\/#website\",\"url\":\"https:\/\/vapehosale.com\/\",\"name\":\"Vape Wholesale\",\"description\":\"Buy Vape Wholesale Price Near you\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/vapehosale.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JNR Chicha narguil\u00e9 ELFBOX 15000 Puffs Cigarette \u00e9lectronique jetable - Vente en gros de vapos","description":"ELF BOX Chicha Narguil\u00e9 15000 Vape jetable avec de riches saveurs de chicha narguil\u00e9, une batterie rechargeable et des options sans nicotine. Durables et puissantes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vapehosale.com\/fr\/product\/jnr-shisha-hookah-elfbox-15000-puffs\/","og_locale":"fr_FR","og_type":"article","og_title":"JNR Shisha Hookah ELFBOX 15000 Puffs Disposable Vape - Vape Wholesale","og_description":"ELF BOX Shisha Hookah 15000 Disposable Vape with rich hookah shisha flavors, rechargeable battery, and nicotine-free options. Long-lasting, and powerful.","og_url":"https:\/\/vapehosale.com\/fr\/product\/jnr-shisha-hookah-elfbox-15000-puffs\/","og_site_name":"Vape Wholesale","article_modified_time":"2025-08-11T08:35:44+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/10\/ELF-BOX-Shisha-Hookah-15000-Vape-Flavors.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vapehosale.com\/product\/jnr-shisha-hookah-elfbox-15000-puffs\/","url":"https:\/\/vapehosale.com\/product\/jnr-shisha-hookah-elfbox-15000-puffs\/","name":"JNR Chicha narguil\u00e9 ELFBOX 15000 Puffs Cigarette \u00e9lectronique jetable - Vente en gros de vapos","isPartOf":{"@id":"https:\/\/vapehosale.com\/#website"},"datePublished":"2024-10-17T07:31:44+00:00","dateModified":"2025-08-11T08:35:44+00:00","description":"ELF BOX Chicha Narguil\u00e9 15000 Vape jetable avec de riches saveurs de chicha narguil\u00e9, une batterie rechargeable et des options sans nicotine. Durables et puissantes.","breadcrumb":{"@id":"https:\/\/vapehosale.com\/product\/jnr-shisha-hookah-elfbox-15000-puffs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vapehosale.com\/product\/jnr-shisha-hookah-elfbox-15000-puffs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vapehosale.com\/product\/jnr-shisha-hookah-elfbox-15000-puffs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vapehosale.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/vapehosale.com\/vape-shop\/"},{"@type":"ListItem","position":3,"name":"JNR Shisha Hookah ELFBOX 15000 Puffs Disposable Vape"}]},{"@type":"WebSite","@id":"https:\/\/vapehosale.com\/#website","url":"https:\/\/vapehosale.com\/","name":"Vente en gros de vapoteuses","description":"Acheter une cigarette \u00e9lectronique au prix de gros pr\u00e8s de chez vous","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vapehosale.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"}]}},"uagb_featured_image_src":{"full":["https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/10\/ELF-BOX-Shisha-Hookah-15000-Vape-Flavors.jpg",900,900,false],"thumbnail":["https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/10\/ELF-BOX-Shisha-Hookah-15000-Vape-Flavors-150x150.jpg",150,150,true],"medium":["https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/10\/ELF-BOX-Shisha-Hookah-15000-Vape-Flavors-300x300.jpg",300,300,true],"medium_large":["https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/10\/ELF-BOX-Shisha-Hookah-15000-Vape-Flavors-768x768.jpg",768,768,true],"large":["https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/10\/ELF-BOX-Shisha-Hookah-15000-Vape-Flavors.jpg",900,900,false],"1536x1536":["https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/10\/ELF-BOX-Shisha-Hookah-15000-Vape-Flavors.jpg",900,900,false],"2048x2048":["https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/10\/ELF-BOX-Shisha-Hookah-15000-Vape-Flavors.jpg",900,900,false],"trp-custom-language-flag":["https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/10\/ELF-BOX-Shisha-Hookah-15000-Vape-Flavors.jpg",12,12,false],"woocommerce_thumbnail":["https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/10\/ELF-BOX-Shisha-Hookah-15000-Vape-Flavors-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/10\/ELF-BOX-Shisha-Hookah-15000-Vape-Flavors-600x600.jpg",600,600,true],"woocommerce_gallery_thumbnail":["https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/10\/ELF-BOX-Shisha-Hookah-15000-Vape-Flavors-100x100.jpg",100,100,true],"wcpr-photo-reviews":["https:\/\/vapehosale.com\/wp-content\/uploads\/2024\/10\/ELF-BOX-Shisha-Hookah-15000-Vape-Flavors.jpg",500,500,false]},"uagb_author_info":{"display_name":"Vicky hosale","author_link":"https:\/\/vapehosale.com\/fr\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"ELFBOX 15000 Puffs Disposable Vape offers up to 15000 puffs with 26ml e-liquid, a 0.6ohm mesh coil, and rechargeable Type-C battery. Available in nicotine-free options for a premium hookah shisha experience(website price not include shipping cost) contact me for min order only 50 pcs! not sale under 50pcs, Wholesale only! &nbsp;","_links":{"self":[{"href":"https:\/\/vapehosale.com\/fr\/wp-json\/wp\/v2\/product\/3047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vapehosale.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vapehosale.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/vapehosale.com\/fr\/wp-json\/wp\/v2\/comments?post=3047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vapehosale.com\/fr\/wp-json\/wp\/v2\/media\/3050"}],"wp:attachment":[{"href":"https:\/\/vapehosale.com\/fr\/wp-json\/wp\/v2\/media?parent=3047"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vapehosale.com\/fr\/wp-json\/wp\/v2\/product_cat?post=3047"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vapehosale.com\/fr\/wp-json\/wp\/v2\/product_tag?post=3047"}],"curies":[{"name":"Bien jou\u00e9","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}